{"id":52645,"date":"2026-07-15T13:29:37","date_gmt":"2026-07-15T16:29:37","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/duelo-entre-argentina-e-inglaterra-e-prova-de-fogo-contra-o-racismo\/"},"modified":"2026-07-15T13:29:37","modified_gmt":"2026-07-15T16:29:37","slug":"duelo-entre-argentina-e-inglaterra-e-prova-de-fogo-contra-o-racismo","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/duelo-entre-argentina-e-inglaterra-e-prova-de-fogo-contra-o-racismo\/","title":{"rendered":"Duelo entre Argentina e Inglaterra \u00e9 prova de fogo contra o racismo"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div>\n<p>A sele\u00e7\u00e3o inglesa de futebol entra em campo nesta quarta-feira (15) contra a sele\u00e7\u00e3o da Argentina, \u00e0s 16h, e os olhos do mundo se voltam tanto para o experiente Lionel Messi, da albiceleste, que faz sua \u00faltima Copa do Mundo, quanto para a estrela inglesa, o meio-campo Jude Bellingham.\u00a0<\/p>\n<p><strong>Aos 23 anos, ele superou hostilidades em seu pa\u00eds e se tornou um \u00edcone<\/strong>, cuja torcida lhe homenageia cantando a can\u00e7\u00e3o dos Beatles <em>Hey Jude<\/em>, uma das mais famosas da banda de rock.<\/p>\n<p><strong>Bellingham, um negro, que saiu cedo do pa\u00eds, enfrentou uma onda de cr\u00edticas, ao ser convocado, at\u00e9 se destacar em campo, sendo decisivo na vit\u00f3ria contra o Mexico, marcando dois dos tr\u00eas gols da vit\u00f3ria, no domingo (5), no Est\u00e1dio Asteca.<\/strong>\u00a0<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/comite-faz-operacao-em-sao-paulo-contra-fraude-no-icms\/\">Comit\u00ea faz opera\u00e7\u00e3o em S\u00e3o Paulo contra fraude no ICMS<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\">Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes<\/a><\/strong><\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<h6 class=\"meta\"><!--copyright=307989-->Meio-campista da sele\u00e7\u00e3o da Inglaterra Jude Bellingham \u2013 Foto:\u00a0<strong>Reuters\/Molly Darlington\/direitos reservados<\/strong><!--END copyright=307989--><\/h6>\n<\/div>\n<p><strong>Fora dos gramados, Jude tamb\u00e9m tem se sobressa\u00eddo pela voz firme contra o racismo, direcionado a si e a colegas<\/strong>, tendo, antes da Copa, apoiado outras v\u00edtimas, como o jogador brasileiro Vini Jr., com quem joga lado a lado no campeonato espanhol.\u00a0<\/p>\n<p>Messi, por sua vez, vem sendo questionado por n\u00e3o se posicionar contr\u00e1rio a atos racistas, inclusive, de parte da torcida argentina, registrados duas vezes neste mundial. Uma contra um influenciador negro na arquibancada, IShowSpeed, e outra, contra torcedores eg\u00edpcios.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/artigo-como-dar-conta-da-comunicacao-publica\/\">Artigo: Como dar conta da comunica\u00e7\u00e3o p\u00fablica?<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/operacao-mira-lavagem-de-r-100-milhoes-provenientes-de-faccoes\/\">Opera\u00e7\u00e3o mira lavagem de R$ 100 milh\u00f5es provenientes de fac\u00e7\u00f5es<\/a><\/strong><\/p>\n<p>Ao jornal <em>The Guardian<\/em>, Bellingham confessou que recebe mensagens racistas na maioria dos jogos. A quantidade, contou, varia de acordo com seus resultados em campo.\u00a0<\/p>\n<p><strong>\u201cN\u00e3o acho que exista uma \u00fanica profiss\u00e3o no mundo em que voc\u00ea merece ser criticado por racismo\u201d, lamentou.<\/strong> \u201cMas, sabe, esse \u00e9 o mundo em que vivemos e \u00e9 por isso que precisamos fazer mais. As pessoas no poder precisam fazer mais\u201d, acrescentou.<\/p>\n<p>O apoio das torcidas aos jogadores de diferentes origens \u00e9tnicas, principalmente negros, varia de acordo com o resultado das partidas, confirma Marcelo Carvalho, diretor-executivo da organiza\u00e7\u00e3o brasileira Observat\u00f3rio da Discrimina\u00e7\u00e3o Racial no Futebol.\u00a0<\/p>\n<p><strong>Ele v\u00ea avan\u00e7os no combate ao racismo no futebol ingl\u00eas, que est\u00e1 \u201c\u00e0 frente dos demais pa\u00edses\u201d por ter lan\u00e7ado, em 2021, um plano ousado.<\/strong> Por\u00e9m, suspeita do apoio a Bellingham.\u00a0<\/p>\n<p>\u201cN\u00e3o tor\u00e7o para a Inglaterra perder, mas, se perder, veremos se esse apoio vai continuar\u201d, avalia.\u00a0<\/p>\n<blockquote>\n<p>\u201cTemos exemplos nesta Copa de jogadores holandeses, que perderam e foram ofendidos\u201d, lembrou o diretor.<\/p>\n<\/blockquote>\n<p>\u201cIsso tamb\u00e9m j\u00e1 aconteceu na Inglaterra, em 2021. Os ataques surgem na derrota\u201d, disse.<\/p>\n<p>Ao observar os casos de racismo no mundial, o especialista ressaltou ainda que, <strong>pela postura fora de campo, de se posicionar em causas, uma parte do p\u00fablico do futebol tenta colar em Jude a imagem de \u201carrogante\u201d<\/strong>, o que acontece com muitos homens negros.\u00a0<\/p>\n<p>\u201cAs pessoas querem ver negros mostrando subordina\u00e7\u00e3o. A partir do momento que voc\u00ea se posiciona e usa a sua voz, voc\u00ea desafia a ordem\u201d, explicou.<\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<h6 class=\"meta\">Jogador Vini Jr. \u00e9 alvo constante de discrimina\u00e7\u00e3o racial \u2013 Foto:\u00a0<strong>Bruno Peres\/Ag\u00eancia Brasil<\/strong><!--END copyright=418187--><\/h6>\n<\/div>\n<p><strong>O racismo \u00e9 um tema que marcou esta edi\u00e7\u00e3o da Copa.<\/strong> Jogadores holandeses, alem\u00e3es e mesmo ingleses, foram alvos de insultos. Grandes nomes, como o franc\u00eas Kyllian Mbapp\u00e9, sofreram insultos diretos, c\u00e2nticos racistas foram entoados por torcidas e ainda houve o veto dos Estados Unidos, pa\u00eds sede da competi\u00e7\u00e3o, \u00e0 entrada no pa\u00eds do \u00e1rbitro somali Omar Abdulkadir Artan.<\/p>\n<p>Longe dos gramados, os n\u00fameros comprovam o cen\u00e1rio. <strong>A Fifa identificou e removeu 89 mil publica\u00e7\u00f5es abusivas nas redes sociais durante a fase de grupos<\/strong>, um aumento de 13 vezes em rela\u00e7\u00e3o \u00e0 edi\u00e7\u00e3o de 2022, no Catar.\u00a0<\/p>\n<p>O registro foi feito pelo Servi\u00e7o de Prote\u00e7\u00e3o \u00e0s Redes Sociais, criado na Copa passada, que analisou 6 milh\u00f5es de publica\u00e7\u00f5es. Os coment\u00e1rios racistas eram 11% do total de mensagens ofensivas, revelou o estudo.<\/p>\n<p>Para a organiza\u00e7\u00e3o inglesa Kick it Out, que tamb\u00e9m monitora casos de racismo no esporte, a a\u00e7\u00e3o da Fifa, de monitoramento, \u00e9 importante, <strong>mas maior responsabiliza\u00e7\u00e3o gera confian\u00e7a para denunciar<\/strong>.<\/p>\n<blockquote>\n<p>\u201cTemporada ap\u00f3s temporada, as pessoas denunciam \u00e0 Kick it Out n\u00famero recorde de casos, e \u00e9 por isso que continuaremos a trabalhar com parceiros para garantir que existam pol\u00edticas mais eficazes para lidar com esses problemas generalizados\u201d, disse a entidade, em um posicionamento p\u00fablico em seu site.<\/p>\n<\/blockquote>\n<p>As organiza\u00e7\u00f5es civis cobram \u201cum esfor\u00e7o coordenado em escala global\u201d, com aux\u00edlio da Fifa, que criou o protocolo Vini Jr., avaliando que o problema requer mais de entidades do futebol, autoridades nacionais e internacionais.\u00a0<\/p>\n<p><strong>Apesar da exist\u00eancia do protocolo claro, na primeira semana da copa um \u00e1rbitro de v\u00eddeo foi alvo de acusa\u00e7\u00f5es ap\u00f3s um gesto racista conhecido. Ele usou os dedos para fazer um s\u00edmbolo comum entre supremacistas brancos.<\/strong>\u00a0<\/p>\n<p>A Fifa investigou o caso, mas concluiu que o ato n\u00e3o foi intencional. At\u00e9 agora, tampouco a torcida Argentina enfrentou san\u00e7\u00f5es.<\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<h6 class=\"meta\">Premier League lan\u00e7ou um plano para combater o racismo no futebol e na sociedade \u2013 Foto:\u00a0<strong>Paulo Pinto\/Ag\u00eancia Brasil<\/strong><!--END copyright=467533--><\/h6>\n<\/div>\n<h2>Pol\u00edtica antirracista<\/h2>\n<p>Para a semifinal entre Argentina e Inglaterra, Marcelo Carvalho, diretor-executivo da organiza\u00e7\u00e3o brasileira Observat\u00f3rio da Discrimina\u00e7\u00e3o Racial no Futebol, espera que, al\u00e9m de destacar jogadores, seja poss\u00edvel dar visibilidade a importantes iniciativas do futebol ingl\u00eas, como a pol\u00edtica antirracista da Premier League, a primeira divis\u00e3o do futebol ingl\u00eas.\u00a0<\/p>\n<p>\u201cA Inglaterra est\u00e1 um passo \u00e0 frente de todos os pa\u00edses no combate ao racismo no futebol\u201d, afirma Marcelo Carvalho.\u00a0<\/p>\n<p><strong>Desde a derrota na Eurocopa, em 2021, a liga de futebol ingl\u00eas Premier League lan\u00e7ou um plano para combater o racismo no futebol e na sociedade.<\/strong>\u00a0<\/p>\n<blockquote>\n<p>\u201cA mensagem \u00e9 clara: n\u00e3o h\u00e1 espa\u00e7o para o racismo. Em lugar nenhum\u201d, afirma a entidade, em seu site.<\/p>\n<\/blockquote>\n<p>A liga planejou a\u00e7\u00f5es de m\u00e9dio prazo e trabalha com clubes, torcedores, organiza\u00e7\u00f5es da sociedade, como a Kick it Out, o sindicato dos jogadores, escolas e a pol\u00edcia, para coibir os ataques. Eles chegaram a identificar autores de ofensas racistas nas redes sociais, cobrando medidas contra os autores.<\/p>\n<p><strong>A entidade tamb\u00e9m d\u00e1 treinamento para \u00e1rbitros, incentiva a\u00e7\u00f5es afirmativas nos clubes, principalmente para incluir mulheres e brit\u00e2nicos de origem asi\u00e1tica, al\u00e9m de fazer campanhas nos dias de jogo.<\/strong>\u00a0<\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<div class=\"dnd-caption-wrapper\">\n<p><!--copyright=273103-->Fifa identificou e removeu 89 mil publica\u00e7\u00f5es abusivas nas redes sociais durante a fase de grupos \u2013 Foto:\u00a0<strong>Reuters\/Arnd Wiegmann\/direitos reservados<\/strong><!--END copyright=273103--><\/p>\n<\/div>\n<\/div>\n<p>\u201cNo campeonato ingl\u00eas, vemos mensagens contra o racismo em todos os jogos e tamb\u00e9m contra a LGBTfobia\u201d, disse Carvalho.\u00a0<\/p>\n<p>\u201cA Inglaterra est\u00e1 \u00e0 frente entre os pa\u00edses e, talvez, por isso, jogadores como Bellingham consigam se posicionar\u201d, afirmou.<\/p>\n<p><strong>A liga tamb\u00e9m mant\u00e9m um site para que torcedores relatem casos de discrimina\u00e7\u00e3o que s\u00e3o investigados por especialistas e levados ao Estado ingl\u00eas.<\/strong><\/p>\n<p>\u201cTemos avan\u00e7ado, mas devemos permanecer determinados a combater a discrimina\u00e7\u00e3o com coragem e consist\u00eancia\u201d, afirma a organiza\u00e7\u00e3o inglesa Kick it Out.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews A sele\u00e7\u00e3o inglesa de futebol entra em campo nesta quarta-feira (15) contra a sele\u00e7\u00e3o da Argentina, \u00e0s 16h, e os olhos do mundo se voltam tanto para o experiente Lionel Messi, da albiceleste, que faz sua \u00faltima Copa do Mundo, quanto para a estrela inglesa, o meio-campo Jude Bellingham.\u00a0 Aos 23 anos, ele [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52645","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52645"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52645\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}