{"id":52646,"date":"2026-07-15T13:55:43","date_gmt":"2026-07-15T16:55:43","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/autorizacao-de-inexigibilidade-de-licitacao-no-20-2026-prefeitura-municipal-de-bonito\/"},"modified":"2026-07-15T13:55:43","modified_gmt":"2026-07-15T16:55:43","slug":"autorizacao-de-inexigibilidade-de-licitacao-no-20-2026-prefeitura-municipal-de-bonito","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/autorizacao-de-inexigibilidade-de-licitacao-no-20-2026-prefeitura-municipal-de-bonito\/","title":{"rendered":"AUTORIZA\u00c7\u00c3O DE INEXIGIBILIDADE DE LICITA\u00c7\u00c3O N\u00ba 20\/2026 &#8211; Prefeitura Municipal de Bonito"},"content":{"rendered":"<p><\/p>\n<div data-td-block-uid=\"tdi_60\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p class=\"wp-block-paragraph\">Reconhe\u00e7o a inexigibilidade de licita\u00e7\u00e3o, fundamentada no artigo 74, inciso II, da Lei n\u00ba 14133\/21, conforme solicita\u00e7\u00e3o, justificativa e parecer jur\u00eddico, constantes no processo abaixo, tendo como objeto a <strong>contrata\u00e7\u00e3o da empresa \u201cMAA PRODU\u00c7\u00d5ES ART\u00cdSTICAS LTDA\u201d para realiza\u00e7\u00e3o de show art\u00edstico da dupla \u201cHUMBERTO &amp; RONALDO\u201d, para apresenta\u00e7\u00e3o musical no dia 30 de agosto de 2026, durante a programa\u00e7\u00e3o do 25\u00ba Festival de Inverno de Bonito \u2013 FIB, no Munic\u00edpio de Bonito\/MS.<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><strong>AUTORIZO<\/strong> a despesa, em cumprimento \u00e0s determina\u00e7\u00f5es contidas na Lei retro mencionada.<\/p>\n<p class=\"wp-block-paragraph\"><strong>INEXIGIBILIDADE DE LICITA\u00c7\u00c3O<\/strong><strong> N\u00ba 20\/2026<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><strong>PROCESSO LICITAT\u00d3RIO N\u00ba 76\/2026<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><strong>FAVORECIDO<\/strong>: MAA PRODU\u00c7\u00d5ES ART\u00cdSTICAS LTDA<\/p>\n<p class=\"wp-block-paragraph\"><strong>CNPJ N\u00ba <\/strong>22.316.617\/0001-53<\/p>\n<p class=\"wp-block-paragraph\"><strong>VALOR: <\/strong>R$ 463.000,00 (quatrocentos e sessenta e tr\u00eas mil reais).<\/p>\n<p class=\"wp-block-paragraph\"><strong>PRAZO<\/strong>: 90 dias.<\/p>\n<p class=\"wp-block-paragraph\">Bonito-MS, 15 de julho de 2026.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Josmail Rodrigues<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Prefeito Municipal.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Reconhe\u00e7o a inexigibilidade de licita\u00e7\u00e3o, fundamentada no artigo 74, inciso II, da Lei n\u00ba 14133\/21, conforme solicita\u00e7\u00e3o, justificativa e parecer jur\u00eddico, constantes no processo abaixo, tendo como objeto a contrata\u00e7\u00e3o da empresa \u201cMAA PRODU\u00c7\u00d5ES ART\u00cdSTICAS LTDA\u201d para realiza\u00e7\u00e3o de show art\u00edstico da dupla \u201cHUMBERTO &amp; RONALDO\u201d, para apresenta\u00e7\u00e3o musical no dia 30 de agosto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-52646","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52646"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52646\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}