{"id":52647,"date":"2026-07-15T14:37:40","date_gmt":"2026-07-15T17:37:40","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/defesa-civil-alerta-para-vendaval-a-partir-desta-quinta-feira-16-cgnoticias\/"},"modified":"2026-07-15T14:37:40","modified_gmt":"2026-07-15T17:37:40","slug":"defesa-civil-alerta-para-vendaval-a-partir-desta-quinta-feira-16-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/07\/15\/defesa-civil-alerta-para-vendaval-a-partir-desta-quinta-feira-16-cgnoticias\/","title":{"rendered":"Defesa Civil alerta para vendaval a partir desta quinta-feira (16) \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Coordenadoria Municipal de Prote\u00e7\u00e3o e Defesa Civil alerta para o risco de vendaval em Campo Grande entre as 23h desta quinta-feira (16) e as 22h59 de domingo (19). O alerta laranja foi emitido pelo Instituto Nacional de Meteorologia (Inmet) e prev\u00ea ventos entre 60 km\/h e 100 km\/h.<\/p>\n<p>De acordo com o aviso meteorol\u00f3gico, h\u00e1 risco de queda de \u00e1rvores, destelhamento de resid\u00eancias e danos em edifica\u00e7\u00f5es e planta\u00e7\u00f5es em decorr\u00eancia da intensidade dos ventos.<\/p>\n<p>A Defesa Civil orienta que a popula\u00e7\u00e3o redobre os cuidados durante o per\u00edodo de vig\u00eancia do alerta, evitando permanecer pr\u00f3ximo a \u00e1rvores, estruturas met\u00e1licas, placas de publicidade e locais com risco de queda de objetos.<\/p>\n<p>Em caso de ocorr\u00eancias, a popula\u00e7\u00e3o pode acionar a Defesa Civil pelo telefone 199. Para solicita\u00e7\u00e3o de servi\u00e7os p\u00fablicos, o atendimento \u00e9 realizado pelo 156. J\u00e1 em situa\u00e7\u00f5es que envolvam risco na rede el\u00e9trica, o contato deve ser feito diretamente com a concession\u00e1ria de energia, pelo telefone 193.<\/p>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Coordenadoria Municipal de Prote\u00e7\u00e3o e Defesa Civil alerta para o risco de vendaval em Campo Grande entre as 23h desta quinta-feira (16) e as 22h59 de domingo (19). O alerta laranja foi emitido pelo Instituto Nacional de Meteorologia (Inmet) e prev\u00ea ventos entre 60 km\/h e 100 km\/h. De acordo com o aviso meteorol\u00f3gico, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-52647","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52647"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52647\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}