{"id":54335,"date":"2026-09-01T16:05:35","date_gmt":"2026-09-01T19:05:35","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/09\/01\/fumace-percorre-bairros-de-campo-grande-nesta-terca-feira-cgnoticias\/"},"modified":"2026-09-01T16:05:35","modified_gmt":"2026-09-01T19:05:35","slug":"fumace-percorre-bairros-de-campo-grande-nesta-terca-feira-cgnoticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/09\/01\/fumace-percorre-bairros-de-campo-grande-nesta-terca-feira-cgnoticias\/","title":{"rendered":"Fumac\u00ea percorre bairros de Campo Grande nesta ter\u00e7a-feira \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O combate ao mosquito Aedes aegypti, transmissor da dengue, zika e chikungunya, ser\u00e1 refor\u00e7ado nesta ter\u00e7a-feira (1\u00ba) em bairros de Campo Grande com a aplica\u00e7\u00e3o do servi\u00e7o de borrifa\u00e7\u00e3o ultrabaixo volume (UBV), conhecido como Fumac\u00ea.<\/p>\n<p>As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV), da Secretaria Municipal de Sa\u00fade (Sesau), circular\u00e3o das 16h \u00e0s 22h pelas ruas dos bairros Carlota, Dr. Albuquerque e Universit\u00e1rio.<\/p>\n<p>Para aumentar a efic\u00e1cia da aplica\u00e7\u00e3o do inseticida, a orienta\u00e7\u00e3o aos moradores \u00e9 para que mantenham portas e janelas abertas durante a passagem dos ve\u00edculos. Dessa forma, o produto consegue alcan\u00e7ar os locais onde h\u00e1 maior probabilidade de presen\u00e7a dos mosquitos.<\/p>\n<p>A programa\u00e7\u00e3o pode ser adiada ou cancelada em caso de chuva, ventos fortes ou neblina, condi\u00e7\u00f5es clim\u00e1ticas que prejudicam a aplica\u00e7\u00e3o do inseticida.<\/p>\n<p>O produto utilizado no servi\u00e7o atinge os mosquitos adultos, principalmente as f\u00eameas, respons\u00e1veis pela transmiss\u00e3o das doen\u00e7as. Por se tratar de uma aplica\u00e7\u00e3o criteriosa, outras esp\u00e9cies tamb\u00e9m podem ser atingidas.<\/p>\n<p><strong>Confira o itiner\u00e1rio:<\/strong><\/p>\n<figure class=\"wp-block-image size-full\"><\/figure>\n<p><em>#ParaTodosVeem: A imagem de destaque mostra o carro do fumac\u00ea circulando pela cidade.\u00a0<\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O combate ao mosquito Aedes aegypti, transmissor da dengue, zika e chikungunya, ser\u00e1 refor\u00e7ado nesta ter\u00e7a-feira (1\u00ba) em bairros de Campo Grande com a aplica\u00e7\u00e3o do servi\u00e7o de borrifa\u00e7\u00e3o ultrabaixo volume (UBV), conhecido como Fumac\u00ea. As equipes da Coordenadoria de Controle de Endemias Vetoriais (CCEV), da Secretaria Municipal de Sa\u00fade (Sesau), circular\u00e3o das 16h \u00e0s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-54335","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54335"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54335\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}