{"id":54344,"date":"2026-09-01T20:55:35","date_gmt":"2026-09-01T23:55:35","guid":{"rendered":"https:\/\/novasdodia.com.br\/index.php\/2026\/09\/01\/atividade-que-integra-leitura-e-videogame-e-atracao-na-biblioteca-municipal-nesta-quinta-3-e-sexta-feira-4-agencia-de-noticias\/"},"modified":"2026-09-01T20:55:35","modified_gmt":"2026-09-01T23:55:35","slug":"atividade-que-integra-leitura-e-videogame-e-atracao-na-biblioteca-municipal-nesta-quinta-3-e-sexta-feira-4-agencia-de-noticias","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2026\/09\/01\/atividade-que-integra-leitura-e-videogame-e-atracao-na-biblioteca-municipal-nesta-quinta-3-e-sexta-feira-4-agencia-de-noticias\/","title":{"rendered":"Atividade que integra leitura e videogame \u00e9 atra\u00e7\u00e3o na Biblioteca Municipal nesta quinta (3) e sexta-feira (4) \u2013 Ag\u00eancia de Not\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"col\">\n<p class=\"mt-0\">\n\t\t\t\t\t\t<strong><br \/>\n\t\t\t\t\t\t\t<span class=\"far fa-calendar mr-1 mt-2\"\/><br \/>\n\t\t\t\t\t\t\t1 de setembro de 2026<br \/>\n\t\t\t\t\t\t\t<span class=\"far fa-clock ml-3 mt-2\"\/><br \/>\n\t\t\t\t\t\t\t18:00<br \/>\n\t\t\t\t\t\t<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"mb-0\">Por: <strong>Evelyn Azevedo<\/strong><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<p class=\"\">Os mun\u00edcipes ter\u00e3o a oportunidade de participar, nesta quinta (3) e sexta-feira (4), da atividade que integra leitura e videogame na Biblioteca Municipal \u201cJorge Guilherme Senger\u201d, localizada no Alto da Boa Vista. As vagas s\u00e3o limitadas e preenchidas por ordem de chegada.<\/p>\n<p class=\"\">A iniciativa tem como objetivo aproximar a popula\u00e7\u00e3o do rico acervo da Biblioteca Municipal de Sorocaba, al\u00e9m de incentivar o acesso \u00e0 leitura, com propostas art\u00edsticas e l\u00fadicas.<\/p>\n<p class=\"\">A atividade ocorre semanalmente \u00e0s quintas e sextas-feiras, das 9h \u00e0s 16h, com participa\u00e7\u00e3o permitida ao p\u00fablico de at\u00e9 16 anos. A cada minuto de leitura de qualquer livro dispon\u00edvel na unidade, os participantes ter\u00e3o a oportunidade de usar o mesmo tempo para jogar PlayStation 5 ou Xbox.<\/p>\n<p class=\"\">A Biblioteca Municipal \u201cJorge Guilherme Senger\u201d est\u00e1 localizada na Rua Ministro Coqueijo Costa, 180, no Alto da Boa Vista, e funciona de segunda a sexta-feira, das 9h \u00e0s 17h. Mais informa\u00e7\u00f5es podem ser obtidas pelo telefone: (15) 3228-1955.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 de setembro de 2026 18:00 Por: Evelyn Azevedo Os mun\u00edcipes ter\u00e3o a oportunidade de participar, nesta quinta (3) e sexta-feira (4), da atividade que integra leitura e videogame na Biblioteca Municipal \u201cJorge Guilherme Senger\u201d, localizada no Alto da Boa Vista. As vagas s\u00e3o limitadas e preenchidas por ordem de chegada. A iniciativa tem como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-54344","post","type-post","status-publish","format-standard","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54344"}],"version-history":[{"count":0,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54344\/revisions"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}