{"id":9880,"date":"2023-09-09T01:34:04","date_gmt":"2023-09-09T04:34:04","guid":{"rendered":"https:\/\/novasdodia.com.br\/?p=9880"},"modified":"2023-09-09T01:34:04","modified_gmt":"2023-09-09T04:34:04","slug":"vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria-netvasco-bola-rolando","status":"publish","type":"post","link":"https:\/\/novasdodia.com.br\/index.php\/2023\/09\/09\/vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria-netvasco-bola-rolando\/","title":{"rendered":"Vasco parabeniza as cidades de S\u00e3o Lu\u00eds e Vit\u00f3ria | NETVASCO &#8211; BOLA ROLANDO"},"content":{"rendered":"\n<p>Vasco parabeniza as cidades de S\u00e3o Lu\u00eds e Vit\u00f3ria  \t\t\t\t\t\t                        Sexta-feira, 08\/09\/2023  &#8211; 21:42                              \t\t\t\t\tvascodagama    Al\u00f4, minha S\u00e3o Lu\u00eds! \u2764\ud83d\udca2    A capital do estado do Maranh\u00e3o est\u00e1 completando 411 anos nesta sexta-feira! \ud83c\udf89    S\u00e3o Lu\u00eds \u00e9 Vasco!  Maranh\u00e3o \u00e9 Vasco!    #VascoDaGama    <\/p>\n<table>\n<tr>\n<td><a><\/a><\/td>\n<\/tr>\n<\/table>\n<p>      A nossa querida Vit\u00f3ria est\u00e1 fazendo anivers\u00e1rio! \ud83d\udc4f\ud83d\udca2    A capital do Esp\u00edrito Santo completa 472 anos nesta sexta-feira! \ud83c\udf89    Vit\u00f3ria \u00e9 Vasco! O Esp\u00edrito Santo \u00e9 Vasco!    #VascoDaGama    <\/p>\n<table>\n<tr>\n<td><a><\/a><\/td>\n<\/tr>\n<\/table>\n<p>    Fonte: Instagram oficial do Vasco<\/p>\n<p>Fonte: <a>www.netvasco.com.br\/n\/319909\/vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria<\/a><\/p>\n<p>   \t\t\t\t\t\t\t  \t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\tCategoria<a>vasco<\/a>                        <\/p>\n<p>Fonte: <a href=\"\/\/bolarolando.com.br\/index.php\/2023\/09\/08\/vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria-netvasco\" title=\"bolarolando.com.br\/index.php\/2023\/09\/08\/vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria-netvasco\" target=\"_blank\" rel=\"bookmark noopener\"><cite>bolarolando.com.br\/index.php\/2023\/09\/08\/vasco-parabeniza-as-cidades-de-sao-luis-e-vitoria-netvasco<\/cite><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vasco parabeniza as cidades de S\u00e3o Lu\u00eds e Vit\u00f3ria Sexta-feira, 08\/09\/2023 &#8211; 21:42 vascodagama Al\u00f4, minha S\u00e3o Lu\u00eds! \u2764\ud83d\udca2 A capital do estado do Maranh\u00e3o est\u00e1 completando 411 anos nesta sexta-feira! \ud83c\udf89 S\u00e3o Lu\u00eds \u00e9 Vasco! Maranh\u00e3o \u00e9 Vasco! #VascoDaGama A nossa querida Vit\u00f3ria est\u00e1 fazendo anivers\u00e1rio! \ud83d\udc4f\ud83d\udca2 A capital do Esp\u00edrito Santo completa 472 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9880","post","type-post","status-publish","format-standard","hentry","category-futebol-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9880"}],"version-history":[{"count":1,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9880\/revisions"}],"predecessor-version":[{"id":9881,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9880\/revisions\/9881"}],"wp:attachment":[{"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novasdodia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}